{"id":187,"date":"2020-06-09T10:18:47","date_gmt":"2020-06-09T08:18:47","guid":{"rendered":"https:\/\/ahmad-mansour.de\/?p=187"},"modified":"2020-07-07T10:19:08","modified_gmt":"2020-07-07T08:19:08","slug":"die-realitaet-ist-mehrdimensional","status":"publish","type":"post","link":"https:\/\/ahmad-mansour.de\/en\/2020\/06\/09\/die-realitaet-ist-mehrdimensional\/","title":{"rendered":"Die Realit\u00e4t ist mehrdimensional."},"content":{"rendered":"<p>[vc_row css_animation=&#8221;&#8221; row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; angled_section=&#8221;no&#8221; text_align=&#8221;left&#8221; background_image_as_pattern=&#8221;without_pattern&#8221;][vc_column width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;94&#8243; img_size=&#8221;medium&#8221; style=&#8221;vc_box_rounded&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; qode_css_animation=&#8221;element_from_left&#8221; qode_hover_animation=&#8221;zoom_in&#8221; link=&#8221;https:\/\/taz.de\/Ahmad-Mansour-im-Interview\/!171193\/&#8221;][\/vc_column][vc_column width=&#8221;3\/4&#8243;][vc_column_text]TAZ, 09. Juni 2020<\/p>\n<p>Die Realit\u00e4t ist mehrdimensional.<br \/>\nDer Psychologe Ahmad Mansour \u00fcber die Realit\u00e4t der Integration in Deutschland und seine Lebenserfahrung von vier Shutdowns.[\/vc_column_text]<a  itemprop=\"url\" href=\"https:\/\/taz.de\/Ahmad-Mansour-im-Interview\/!171193\/\" target=\"_blank\"  class=\"qbutton  large default\" style=\"margin: 50px; \">Den ganzen Artikel hier lesen...<\/a>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Realit\u00e4t ist mehrdimensional.<br \/>\nDer Psychologe Ahmad Mansour \u00fcber die Realit\u00e4t der Integration in Deutschland und seine Lebenserfahrung von vier Shutdowns.<\/p>\n","protected":false},"author":1,"featured_media":94,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"_links":{"self":[{"href":"https:\/\/ahmad-mansour.de\/en\/wp-json\/wp\/v2\/posts\/187"}],"collection":[{"href":"https:\/\/ahmad-mansour.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ahmad-mansour.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ahmad-mansour.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ahmad-mansour.de\/en\/wp-json\/wp\/v2\/comments?post=187"}],"version-history":[{"count":0,"href":"https:\/\/ahmad-mansour.de\/en\/wp-json\/wp\/v2\/posts\/187\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ahmad-mansour.de\/en\/wp-json\/wp\/v2\/media\/94"}],"wp:attachment":[{"href":"https:\/\/ahmad-mansour.de\/en\/wp-json\/wp\/v2\/media?parent=187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ahmad-mansour.de\/en\/wp-json\/wp\/v2\/categories?post=187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ahmad-mansour.de\/en\/wp-json\/wp\/v2\/tags?post=187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}